{"id":16458,"date":"2020-07-14T14:31:54","date_gmt":"2020-07-14T12:31:54","guid":{"rendered":"https:\/\/sophietaeuberarp.org\/?p=16458"},"modified":"2020-10-02T09:42:20","modified_gmt":"2020-10-02T07:42:20","slug":"angelica-anna-und-andere-schwestern-von-gestern","status":"publish","type":"post","link":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/","title":{"rendered":"angelica, anna und andere schwestern von gestern"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-16458","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-exhibition","7":"entry"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>angelica, anna und andere schwestern von gestern - STARP EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"angelica, anna und andere schwestern von gestern - STARP EN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/\" \/>\n<meta property=\"og:site_name\" content=\"STARP EN\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-14T12:31:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-02T07:42:20+00:00\" \/>\n<meta name=\"author\" content=\"Anna Schrader\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Schrader\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/\"},\"author\":{\"name\":\"Anna Schrader\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/person\\\/262bfa7aa5cd7d2335782049423ad13f\"},\"headline\":\"angelica, anna und andere schwestern von gestern\",\"datePublished\":\"2020-07-14T12:31:54+00:00\",\"dateModified\":\"2020-10-02T07:42:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/\"},\"wordCount\":7,\"publisher\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#organization\"},\"articleSection\":[\"Ausstellung\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/\",\"name\":\"angelica, anna und andere schwestern von gestern - STARP EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#website\"},\"datePublished\":\"2020-07-14T12:31:54+00:00\",\"dateModified\":\"2020-10-02T07:42:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/angelica-anna-und-andere-schwestern-von-gestern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"angelica, anna und andere schwestern von gestern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#website\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/\",\"name\":\"STARP\",\"description\":\"Sophie EN\",\"publisher\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#organization\",\"name\":\"Stiftung Arp e. V.\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/logo_arp.png\",\"contentUrl\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/logo_arp.png\",\"width\":110,\"height\":40,\"caption\":\"Stiftung Arp e. V.\"},\"image\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/person\\\/262bfa7aa5cd7d2335782049423ad13f\",\"name\":\"Anna Schrader\",\"description\":\"Here is example bio text. Etiam rhoncus. Maecenas tempus, tellus eget condimentum rhoncus, sem quam semper libero, sit amet adipiscing sem neque sed ipsum. Nam quam nunc, blandit vel, luctus pulvinar, hendrerit id, lorem. Maecenas nec odio et ante tincidunt tempus. Donec vitae sapien ut libero venenatis faucibus. Nullam quis ante. Etiam sit amet orci eget eros faucibus tincidunt.\",\"sameAs\":[\"https:\\\/\\\/marcks.de\"],\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/author\\\/annaschrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"angelica, anna und andere schwestern von gestern - STARP EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/","og_locale":"en_GB","og_type":"article","og_title":"angelica, anna und andere schwestern von gestern - STARP EN","og_url":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/","og_site_name":"STARP EN","article_published_time":"2020-07-14T12:31:54+00:00","article_modified_time":"2020-10-02T07:42:20+00:00","author":"Anna Schrader","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Anna Schrader"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/#article","isPartOf":{"@id":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/"},"author":{"name":"Anna Schrader","@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/person\/262bfa7aa5cd7d2335782049423ad13f"},"headline":"angelica, anna und andere schwestern von gestern","datePublished":"2020-07-14T12:31:54+00:00","dateModified":"2020-10-02T07:42:20+00:00","mainEntityOfPage":{"@id":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/"},"wordCount":7,"publisher":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#organization"},"articleSection":["Ausstellung"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/","url":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/","name":"angelica, anna und andere schwestern von gestern - STARP EN","isPartOf":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#website"},"datePublished":"2020-07-14T12:31:54+00:00","dateModified":"2020-10-02T07:42:20+00:00","breadcrumb":{"@id":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sophietaeuberarp.org\/english\/angelica-anna-und-andere-schwestern-von-gestern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/sophietaeuberarp.org\/english\/"},{"@type":"ListItem","position":2,"name":"angelica, anna und andere schwestern von gestern"}]},{"@type":"WebSite","@id":"https:\/\/sophietaeuberarp.org\/english\/#website","url":"https:\/\/sophietaeuberarp.org\/english\/","name":"STARP","description":"Sophie EN","publisher":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sophietaeuberarp.org\/english\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/sophietaeuberarp.org\/english\/#organization","name":"Stiftung Arp e. V.","url":"https:\/\/sophietaeuberarp.org\/english\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/logo\/image\/","url":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/logo_arp.png","contentUrl":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/logo_arp.png","width":110,"height":40,"caption":"Stiftung Arp e. V."},"image":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/person\/262bfa7aa5cd7d2335782049423ad13f","name":"Anna Schrader","description":"Here is example bio text. Etiam rhoncus. Maecenas tempus, tellus eget condimentum rhoncus, sem quam semper libero, sit amet adipiscing sem neque sed ipsum. Nam quam nunc, blandit vel, luctus pulvinar, hendrerit id, lorem. Maecenas nec odio et ante tincidunt tempus. Donec vitae sapien ut libero venenatis faucibus. Nullam quis ante. Etiam sit amet orci eget eros faucibus tincidunt.","sameAs":["https:\/\/marcks.de"],"url":"https:\/\/sophietaeuberarp.org\/english\/author\/annaschrader\/"}]}},"_links":{"self":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts\/16458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/comments?post=16458"}],"version-history":[{"count":1,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts\/16458\/revisions"}],"predecessor-version":[{"id":17720,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts\/16458\/revisions\/17720"}],"wp:attachment":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/media?parent=16458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/categories?post=16458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/tags?post=16458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}