{"id":6423,"date":"2019-10-30T11:43:08","date_gmt":"2019-10-30T11:43:08","guid":{"rendered":"https:\/\/overwinterencyprus.nl\/starp\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/"},"modified":"2024-06-04T09:36:30","modified_gmt":"2024-06-04T07:36:30","slug":"knoten-in-lebendigen-farben-vor-chaotischem-hintergrund","status":"publish","type":"post","link":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/","title":{"rendered":"N\u0153ud en couleurs vives sur fond chaotique"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":22016,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-6423","post","type-post","status-publish","format-standard","has-post-thumbnail","category-werke","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u0153ud en couleurs vives sur fond chaotique - STARP EN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u0153ud en couleurs vives sur fond chaotique - STARP EN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/\" \/>\n<meta property=\"og:site_name\" content=\"STARP EN\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-30T11:43:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-04T07:36:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/sophie-taeuber-arp-5316-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2061\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna Schrader\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna Schrader\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/\"},\"author\":{\"name\":\"Anna Schrader\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/person\\\/262bfa7aa5cd7d2335782049423ad13f\"},\"headline\":\"N\u0153ud en couleurs vives sur fond chaotique\",\"datePublished\":\"2019-10-30T11:43:08+00:00\",\"dateModified\":\"2024-06-04T07:36:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/\"},\"wordCount\":8,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/sophie-taeuber-arp-5316-1-scaled.jpg\",\"articleSection\":[\"Werke\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/\",\"name\":\"N\u0153ud en couleurs vives sur fond chaotique - STARP EN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/sophie-taeuber-arp-5316-1-scaled.jpg\",\"datePublished\":\"2019-10-30T11:43:08+00:00\",\"dateModified\":\"2024-06-04T07:36:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/sophie-taeuber-arp-5316-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/sophie-taeuber-arp-5316-1-scaled.jpg\",\"width\":2560,\"height\":2061,\"caption\":\"Photo: Mick Vincenz \u2013 Arp Museum Bahnhof Rolandseck, Remagen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u0153ud en couleurs vives sur fond chaotique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#website\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/\",\"name\":\"STARP\",\"description\":\"Sophie EN\",\"publisher\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#organization\",\"name\":\"Stiftung Arp e. V.\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/logo_arp.png\",\"contentUrl\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/logo_arp.png\",\"width\":110,\"height\":40,\"caption\":\"Stiftung Arp e. V.\"},\"image\":{\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/#\\\/schema\\\/person\\\/262bfa7aa5cd7d2335782049423ad13f\",\"name\":\"Anna Schrader\",\"description\":\"Here is example bio text. Etiam rhoncus. Maecenas tempus, tellus eget condimentum rhoncus, sem quam semper libero, sit amet adipiscing sem neque sed ipsum. Nam quam nunc, blandit vel, luctus pulvinar, hendrerit id, lorem. Maecenas nec odio et ante tincidunt tempus. Donec vitae sapien ut libero venenatis faucibus. Nullam quis ante. Etiam sit amet orci eget eros faucibus tincidunt.\",\"sameAs\":[\"https:\\\/\\\/marcks.de\"],\"url\":\"https:\\\/\\\/sophietaeuberarp.org\\\/english\\\/author\\\/annaschrader\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u0153ud en couleurs vives sur fond chaotique - STARP EN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/","og_locale":"en_GB","og_type":"article","og_title":"N\u0153ud en couleurs vives sur fond chaotique - STARP EN","og_url":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/","og_site_name":"STARP EN","article_published_time":"2019-10-30T11:43:08+00:00","article_modified_time":"2024-06-04T07:36:30+00:00","og_image":[{"width":2560,"height":2061,"url":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/sophie-taeuber-arp-5316-1-scaled.jpg","type":"image\/jpeg"}],"author":"Anna Schrader","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Anna Schrader","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#article","isPartOf":{"@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/"},"author":{"name":"Anna Schrader","@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/person\/262bfa7aa5cd7d2335782049423ad13f"},"headline":"N\u0153ud en couleurs vives sur fond chaotique","datePublished":"2019-10-30T11:43:08+00:00","dateModified":"2024-06-04T07:36:30+00:00","mainEntityOfPage":{"@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/"},"wordCount":8,"commentCount":0,"publisher":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#organization"},"image":{"@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#primaryimage"},"thumbnailUrl":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/sophie-taeuber-arp-5316-1-scaled.jpg","articleSection":["Werke"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/","url":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/","name":"N\u0153ud en couleurs vives sur fond chaotique - STARP EN","isPartOf":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#primaryimage"},"image":{"@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#primaryimage"},"thumbnailUrl":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/sophie-taeuber-arp-5316-1-scaled.jpg","datePublished":"2019-10-30T11:43:08+00:00","dateModified":"2024-06-04T07:36:30+00:00","breadcrumb":{"@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#primaryimage","url":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/sophie-taeuber-arp-5316-1-scaled.jpg","contentUrl":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/sophie-taeuber-arp-5316-1-scaled.jpg","width":2560,"height":2061,"caption":"Photo: Mick Vincenz \u2013 Arp Museum Bahnhof Rolandseck, Remagen"},{"@type":"BreadcrumbList","@id":"https:\/\/sophietaeuberarp.org\/english\/knoten-in-lebendigen-farben-vor-chaotischem-hintergrund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/sophietaeuberarp.org\/english\/"},{"@type":"ListItem","position":2,"name":"N\u0153ud en couleurs vives sur fond chaotique"}]},{"@type":"WebSite","@id":"https:\/\/sophietaeuberarp.org\/english\/#website","url":"https:\/\/sophietaeuberarp.org\/english\/","name":"STARP","description":"Sophie EN","publisher":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sophietaeuberarp.org\/english\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/sophietaeuberarp.org\/english\/#organization","name":"Stiftung Arp e. V.","url":"https:\/\/sophietaeuberarp.org\/english\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/logo\/image\/","url":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/logo_arp.png","contentUrl":"https:\/\/sophietaeuberarp.org\/english\/wp-content\/uploads\/sites\/3\/logo_arp.png","width":110,"height":40,"caption":"Stiftung Arp e. V."},"image":{"@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sophietaeuberarp.org\/english\/#\/schema\/person\/262bfa7aa5cd7d2335782049423ad13f","name":"Anna Schrader","description":"Here is example bio text. Etiam rhoncus. Maecenas tempus, tellus eget condimentum rhoncus, sem quam semper libero, sit amet adipiscing sem neque sed ipsum. Nam quam nunc, blandit vel, luctus pulvinar, hendrerit id, lorem. Maecenas nec odio et ante tincidunt tempus. Donec vitae sapien ut libero venenatis faucibus. Nullam quis ante. Etiam sit amet orci eget eros faucibus tincidunt.","sameAs":["https:\/\/marcks.de"],"url":"https:\/\/sophietaeuberarp.org\/english\/author\/annaschrader\/"}]}},"_links":{"self":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts\/6423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/comments?post=6423"}],"version-history":[{"count":7,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts\/6423\/revisions"}],"predecessor-version":[{"id":24124,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/posts\/6423\/revisions\/24124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/media\/22016"}],"wp:attachment":[{"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/media?parent=6423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/categories?post=6423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sophietaeuberarp.org\/english\/wp-json\/wp\/v2\/tags?post=6423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}